{"id":1128,"count":20,"description":"","link":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/","name":"Plastique recycl\u00e9","slug":"plastique-recycle","taxonomy":"product_cat","parent":1034,"meta":{"group_of_quantity":""},"menu_order":18,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/\" \/>\n<meta property=\"og:site_name\" content=\"Herstera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/plastique-recycle\\\/\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/plastique-recycle\\\/\",\"name\":\"Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#website\"},\"description\":\"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/plastique-recycle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/plastique-recycle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pots et jardini\u00e8res d'ext\u00e9rieur\",\"item\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/pots-et-jardinieres-dexterieur\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plastique recycl\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/\",\"name\":\"Herstera\",\"description\":\"Passion for pottery\",\"publisher\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#organization\",\"name\":\"Herstera\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/herstera-logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/herstera-logo-1.svg\",\"width\":100,\"height\":100,\"caption\":\"Herstera\"},\"image\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Herstera-Garden-SL-100069356703579\\\/?locale=es_ES\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables","description":"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/","og_locale":"fr_FR","og_type":"article","og_title":"Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables","og_description":"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!","og_url":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/","og_site_name":"Herstera","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/","url":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/","name":"Pots en Plastique Recycl\u00e9 | Jardini\u00e8res Durables","isPartOf":{"@id":"https:\/\/hersteragarden.com\/shop\/fr\/#website"},"description":"D\u00e9couvrez nos pots et jardini\u00e8res en plastique recycl\u00e9 alliant style, durabilit\u00e9 et engagement \u00e9cologique. Acc\u00e9dez \u00e0 la collection!","breadcrumb":{"@id":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/hersteragarden.com\/shop\/fr\/plastique-recycle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hersteragarden.com\/shop\/fr\/"},{"@type":"ListItem","position":2,"name":"Pots et jardini\u00e8res d'ext\u00e9rieur","item":"https:\/\/hersteragarden.com\/shop\/fr\/pots-et-jardinieres-dexterieur\/"},{"@type":"ListItem","position":3,"name":"Plastique recycl\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/hersteragarden.com\/shop\/fr\/#website","url":"https:\/\/hersteragarden.com\/shop\/fr\/","name":"Herstera","description":"Passion for pottery","publisher":{"@id":"https:\/\/hersteragarden.com\/shop\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hersteragarden.com\/shop\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hersteragarden.com\/shop\/fr\/#organization","name":"Herstera","url":"https:\/\/hersteragarden.com\/shop\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hersteragarden.com\/shop\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2023\/03\/herstera-logo-1.svg","contentUrl":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2023\/03\/herstera-logo-1.svg","width":100,"height":100,"caption":"Herstera"},"image":{"@id":"https:\/\/hersteragarden.com\/shop\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Herstera-Garden-SL-100069356703579\/?locale=es_ES"]}]}},"_links":{"self":[{"href":"https:\/\/hersteragarden.com\/shop\/fr\/wp-json\/wp\/v2\/product_cat\/1128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hersteragarden.com\/shop\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/hersteragarden.com\/shop\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/hersteragarden.com\/shop\/fr\/wp-json\/wp\/v2\/product_cat\/1034"}],"wp:post_type":[{"href":"https:\/\/hersteragarden.com\/shop\/fr\/wp-json\/wp\/v2\/product?product_cat=1128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}