{"id":78841,"date":"2025-10-03T08:54:48","date_gmt":"2025-10-03T07:54:48","guid":{"rendered":"https:\/\/hersteragarden.com\/shop\/product\/basket-padua\/"},"modified":"2026-09-02T19:30:40","modified_gmt":"2026-09-02T18:30:40","slug":"basket-padua","status":"publish","type":"product","link":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/","title":{"rendered":"BASKET PADUA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":76746,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1035,1220],"product_tag":[],"class_list":["post-78841","product","type-product","status-publish","has-post-thumbnail","product_cat-indoor-pots","product_cat-wicker","pa_material-wicker","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BASKET PADUA - Herstera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BASKET PADUA - Herstera\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/\" \/>\n<meta property=\"og:site_name\" content=\"Herstera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Herstera-Garden-SL-100069356703579\/?locale=es_ES\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T18:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2025\/10\/37004004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/\",\"name\":\"BASKET PADUA - Herstera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/37004004.jpg\",\"datePublished\":\"2025-10-03T07:54:48+00:00\",\"dateModified\":\"2026-09-02T18:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/37004004.jpg\",\"contentUrl\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/37004004.jpg\",\"width\":1125,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/product\\\/basket-padua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BASKET PADUA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/\",\"name\":\"Herstera\",\"description\":\"Passion for pottery\",\"publisher\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#organization\",\"name\":\"Herstera\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/herstera-logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/herstera-logo-1.svg\",\"width\":100,\"height\":100,\"caption\":\"Herstera\"},\"image\":{\"@id\":\"https:\\\/\\\/hersteragarden.com\\\/shop\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/Herstera-Garden-SL-100069356703579\\\/?locale=es_ES\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BASKET PADUA - Herstera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/","og_locale":"en_US","og_type":"article","og_title":"BASKET PADUA - Herstera","og_url":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/","og_site_name":"Herstera","article_publisher":"https:\/\/www.facebook.com\/p\/Herstera-Garden-SL-100069356703579\/?locale=es_ES","article_modified_time":"2026-09-02T18:30:40+00:00","og_image":[{"width":1125,"height":1125,"url":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2025\/10\/37004004.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/","url":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/","name":"BASKET PADUA - Herstera","isPartOf":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/#primaryimage"},"image":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/#primaryimage"},"thumbnailUrl":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2025\/10\/37004004.jpg","datePublished":"2025-10-03T07:54:48+00:00","dateModified":"2026-09-02T18:30:40+00:00","breadcrumb":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/#primaryimage","url":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2025\/10\/37004004.jpg","contentUrl":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2025\/10\/37004004.jpg","width":1125,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/hersteragarden.com\/shop\/en\/product\/basket-padua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/hersteragarden.com\/shop\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/hersteragarden.com\/shop\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"BASKET PADUA"}]},{"@type":"WebSite","@id":"https:\/\/hersteragarden.com\/shop\/en\/#website","url":"https:\/\/hersteragarden.com\/shop\/en\/","name":"Herstera","description":"Passion for pottery","publisher":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hersteragarden.com\/shop\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hersteragarden.com\/shop\/en\/#organization","name":"Herstera","url":"https:\/\/hersteragarden.com\/shop\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hersteragarden.com\/shop\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2023\/03\/herstera-logo-1.svg","contentUrl":"https:\/\/hersteragarden.com\/shop\/wp-content\/uploads\/2023\/03\/herstera-logo-1.svg","width":100,"height":100,"caption":"Herstera"},"image":{"@id":"https:\/\/hersteragarden.com\/shop\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Herstera-Garden-SL-100069356703579\/?locale=es_ES"]}]}},"_links":{"self":[{"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/product\/78841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/media\/76746"}],"wp:attachment":[{"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/media?parent=78841"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/product_brand?post=78841"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/product_cat?post=78841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hersteragarden.com\/shop\/en\/wp-json\/wp\/v2\/product_tag?post=78841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}